{"id":91,"date":"2024-01-15T13:45:41","date_gmt":"2024-01-15T13:45:41","guid":{"rendered":"https:\/\/workspace.innerconfidence.nl\/?page_id=91"},"modified":"2025-04-25T23:46:48","modified_gmt":"2025-04-25T21:46:48","slug":"contact","status":"publish","type":"page","link":"https:\/\/innerconfidence.nl\/en\/contact\/","title":{"rendered":"Contact"},"content":{"rendered":"<div class=\"theme-wrapper theme-subhero\">\n    <div class=\"container\">\n        <div class=\"row justify-content-center\">\n            <div class=\"col-12 col-md-8\">\n                <h1 class=\"theme-subhero-title\">Get in touch<\/h1>\n                <div class=\"theme-subhero-content\"><p>Want to know more about the Balance Service? Or just curious about Mentali-Time? Send us a message!<\/p>\n<\/div>\n                                <a class=\"theme-subhero-hashlink\" href=\"#contact\"><\/a>\n                            <\/div>\n        <\/div>\n    <\/div>\n<\/div>\n\n<div class=\"theme-wrapper theme-contact\" id=\"contact\">\n    <div class=\"container\">\n        <div class=\"row\">\n            <div class=\"col-12 col-lg-6\">\n                <h2 class=\"theme-contact-title\">Contact details<\/h2>\n                <div class=\"theme-contact-wrapper\">\n                    <div class=\"theme-contact-wrapper-image\">\n                        <img decoding=\"async\" src=\"https:\/\/innerconfidence.nl\/wp-content\/uploads\/2024\/01\/Enrique-E.jpeg\" alt=\"Contact image\">\n                    <\/div>\n                    <div class=\"theme-contact-wrapper-content\">\n                        <h2 class=\"theme-contact-wrapper-content-name\">Enrique Eckenbach<\/h2>\n                        <h3 class=\"theme-contact-wrapper-content-subtitle\">Personal Guide <\/h3>\n                        <ul class=\"theme-contact-wrapper-content-list\">\n                                                    <li class=\"theme-contact-wrapper-content-list-item\"><p><a href=\"mailto:info@innerconfidence.nl\">info@innerconfidence.nl<\/a><\/p>\n<\/li>\n                                                    <li class=\"theme-contact-wrapper-content-list-item\"><p><a href=\"tel:310634266105\">+31 (0)6 342 66 105<\/a><\/p>\n<\/li>\n                                                    <li class=\"theme-contact-wrapper-content-list-item\"><p>Havermarkt 25b<\/p>\n<\/li>\n                                                    <li class=\"theme-contact-wrapper-content-list-item\"><p>4811 WG, Breda<\/p>\n<\/li>\n                                                <\/ul>\n                        <div class=\"theme-contact-wrapper-content-socials\">\n                                                        <a href=\"https:\/\/www.facebook.com\/innerconfidencenl\/\" class=\"theme-contact-wrapper-content-socials-icon facebook\">\n                                <i class=\"fa-brands fa-facebook\"><\/i>\n                            <\/a>\n                                                                                                                                            <a href=\"https:\/\/nl.linkedin.com\/company\/innerconfidence-nl\" class=\"theme-contact-wrapper-content-socials-icon linkedin\">\n                                <i class=\"fa-brands fa-linkedin-in\"><\/i>\n                            <\/a>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n            <div class=\"col-12 col-lg-6\">\n                <div class=\"theme-contact-formwrapper\">\n                    <div class='fluentform ff-default fluentform_wrapper_2 ffs_default_wrap'><form data-form_id=\"2\" id=\"fluentform_2\" class=\"frm-fluent-form fluent_form_2 ff-el-form-top ff_form_instance_2_1 ff-form-loading ffs_default\" data-form_instance=\"ff_form_instance_2_1\" method=\"POST\" action=\"\" ><fieldset  style=\"border: none!important;margin: 0!important;padding: 0!important;background-color: transparent!important;box-shadow: none!important;outline: none!important; min-inline-size: 100%;\">\n                    <legend class=\"ff_screen_reader_title\" style=\"display: block; margin: 0!important;padding: 0!important;height: 0!important;text-indent: -999999px;width: 0!important;overflow:hidden;\">Contact form<\/legend><input type='hidden' name='__fluent_form_embded_post_id' value='91' \/><input type=\"hidden\" id=\"_fluentform_2_fluentformnonce\" name=\"_fluentform_2_fluentformnonce\" value=\"801be03149\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/en\/wp-json\/wp\/v2\/pages\/91\" \/><div data-type=\"name-element\" data-name=\"names\" class=\"ff-field_container ff-name-field-wrapper\" ><div class='ff-t-container'><div class='ff-t-cell'><div class='ff-el-group  ff-el-form-top'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_2_names_first_name_' >Your name<\/label><\/div><div class='ff-el-input--content'><input type=\"text\" name=\"names[first_name]\" id=\"ff_2_names_first_name_\" class=\"ff-el-form-control\" aria-invalid=\"false\" aria-required=\"true\"><\/div><\/div><\/div><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_2_email' aria-label=\"Your email address\">Your email address<\/label><\/div><div class='ff-el-input--content'><input type=\"email\" name=\"email\" id=\"ff_2_email\" class=\"ff-el-form-control\" data-name=\"email\"  aria-invalid=\"false\" aria-required=\"true\"><\/div><\/div><div class='ff-el-group'><div class=\"ff-el-input--label ff-el-is-required asterisk-right\"><label for='ff_2_Bericht' aria-label=\"Write a message\">Write a message<\/label><\/div><div class='ff-el-input--content'><textarea aria-invalid=\"false\" aria-required=\"true\" name=\"Bericht\" id=\"ff_2_Bericht\" class=\"ff-el-form-control\" rows=\"6\" cols=\"1\" data-name=\"Bericht\" ><\/textarea><\/div><\/div><div class='ff-el-group ff-text-left ff_submit_btn_wrapper'><button type=\"submit\" class=\"ff-btn ff-btn-submit ff-btn-md theme-button theme-button__green ff_btn_style\" >Send<\/button><\/div><\/fieldset><input type=\"hidden\" name=\"trp-form-language\" value=\"en\"\/><\/form><div id='fluentform_2_errors' class='ff-errors-in-stack ff_form_instance_2_1 ff-form-loading_errors ff_form_instance_2_1_errors'><\/div><\/div>            <script type=\"text\/javascript\">\n                window.fluent_form_ff_form_instance_2_1 = {\"id\":\"2\",\"settings\":{\"layout\":{\"labelPlacement\":\"top\",\"helpMessagePlacement\":\"with_label\",\"errorMessagePlacement\":\"inline\",\"asteriskPlacement\":\"asterisk-right\"},\"restrictions\":{\"denyEmptySubmission\":{\"enabled\":false}}},\"form_instance\":\"ff_form_instance_2_1\",\"form_id_selector\":\"fluentform_2\",\"rules\":{\"names[first_name]\":{\"required\":{\"value\":true,\"message\":\"Dit veld is vereist\",\"global_message\":\"This field is required\",\"global\":false}},\"names[middle_name]\":{\"required\":{\"value\":false,\"message\":\"This field is required\",\"global_message\":\"This field is required\",\"global\":true}},\"names[last_name]\":{\"required\":{\"value\":false,\"message\":\"This field is required\",\"global_message\":\"This field is required\",\"global\":true}},\"email\":{\"required\":{\"value\":true,\"message\":\"Dit veld is vereist\",\"global_message\":\"This field is required\",\"global\":false},\"email\":{\"value\":true,\"message\":\"Dit veld moet een geldig e-mailadres bevatten\",\"global_message\":\"This field must contain a valid email\",\"global\":false}},\"Bericht\":{\"required\":{\"value\":true,\"message\":\"Dit veld is vereist\",\"global_message\":\"This field is required\",\"global\":false}}},\"debounce_time\":300};\n                            <\/script>\n                            <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-91","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/innerconfidence.nl\/en\/wp-json\/wp\/v2\/pages\/91","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/innerconfidence.nl\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/innerconfidence.nl\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/innerconfidence.nl\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/innerconfidence.nl\/en\/wp-json\/wp\/v2\/comments?post=91"}],"version-history":[{"count":13,"href":"https:\/\/innerconfidence.nl\/en\/wp-json\/wp\/v2\/pages\/91\/revisions"}],"predecessor-version":[{"id":961,"href":"https:\/\/innerconfidence.nl\/en\/wp-json\/wp\/v2\/pages\/91\/revisions\/961"}],"wp:attachment":[{"href":"https:\/\/innerconfidence.nl\/en\/wp-json\/wp\/v2\/media?parent=91"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}